{"id":3293,"date":"2025-10-09T16:26:06","date_gmt":"2025-10-09T16:26:06","guid":{"rendered":"https:\/\/defensetechforukraine.org\/?p=3293"},"modified":"2025-10-09T23:17:49","modified_gmt":"2025-10-09T23:17:49","slug":"anti-fiber-drone-technologies-hackathon-innovating-the-next-line-of-defense-in-lviv","status":"publish","type":"post","link":"https:\/\/defensetechforukraine.org\/it\/product-development\/anti-fiber-drone-technologies-hackathon-innovating-the-next-line-of-defense-in-lviv\/","title":{"rendered":"Hackathon sulle tecnologie dei droni anti-fibra: innovare la prossima linea di difesa a Leopoli"},"content":{"rendered":"<p>Il fronte tecnologico dell&#039;Ucraina si sta preparando per una nuova ondata di innovazione sul campo di battaglia. <strong>Laboratori Kaizen<\/strong>, in collaborazione con <strong>Tecnologia di difesa per l&#039;Ucraina<\/strong>, <strong>Libert\u00e0 made in America<\/strong>e altre importanti organizzazioni di difesa, hanno annunciato la <strong>Hackathon sulle tecnologie dei droni anti-fibra<\/strong>, una sfida ingegneristica di 72 ore per sviluppare sistemi anti-UAV pronti per il campo contro le minacce dei droni in fibra ottica.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Innovazione per il campo di battaglia moderno<\/strong><\/h3>\n\n\n\n<p>Ambientato in <strong>Leopoli, Ucraina<\/strong>, l&#039;evento riunir\u00e0 partecipanti in presenza e da remoto per un&#039;intensa <strong>sprint di sviluppo di 72 ore<\/strong> concentrati sulla difesa contro il crescente pericolo di <strong>UAV collegati in fibra<\/strong>\u2014una nuova generazione di droni in grado di aggirare i metodi di disturbo tradizionali.<\/p>\n\n\n\n<p>L&#039;hackathon invita i team a creare progetti innovativi <strong>tecnologie anti-droni<\/strong> che si integrano direttamente con il Kaizen <strong>Drone Sentinel<\/strong> sistema di rilevamento acustico tramite <strong>Reti mesh LoRaWan<\/strong> utilizzando il <strong>Protocollo Meshtastic<\/strong>I partecipanti sono incoraggiati a costruire sistemi che rispondano automaticamente al rilevamento acustico dei droni, consentendo misure difensive rapide e autonome sul campo di battaglia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Tecnologie target<\/strong><\/h3>\n\n\n\n<p>I partecipanti si concentreranno su sistemi anti-drone innovativi come:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Sistemi di difesa contro i droni che tagliano la fibra<\/li>\n\n\n\n<li>Neutralizzazione basata sul laser (accecamento della telecamera, danni all&#039;elica o interruzione dell&#039;elettronica)<\/li>\n\n\n\n<li>Dispositivi anti-drone EMP<\/li>\n\n\n\n<li>Intercettori di droni basati sulla rete<\/li>\n\n\n\n<li>Sistemi acustici di abbattimento dei droni<\/li>\n\n\n\n<li>Altre soluzioni innovative anti-UAV<\/li>\n<\/ul>\n\n\n\n<p>L&#039;enfasi \u00e8 su <strong>progetti a basso costo e implementabili sul campo<\/strong> che pu\u00f2 integrarsi in <strong>Le reti di difesa di prima linea dell&#039;Ucraina<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/download-5-1024x682.jpeg\" alt=\"\" class=\"wp-image-3318\" srcset=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/download-5-1024x682.jpeg 1024w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/download-5-300x200.jpeg 300w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/download-5-768x512.jpeg 768w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/download-5-18x12.jpeg 18w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/download-5.jpeg 1100w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Formato dell&#039;evento e scadenze<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\ud83d\udccd <strong>Posizione:<\/strong> Leopoli, Ucraina (il sito esatto \u00e8 condiviso privatamente per motivi di sicurezza)<\/li>\n\n\n\n<li>\ud83d\udd53 <strong>Durata:<\/strong> Sprint hackathon di 72 ore<\/li>\n\n\n\n<li>\ud83d\udcc5 <strong>Giorno della dimostrazione:<\/strong> Sabato 25 ottobre 2024<\/li>\n\n\n\n<li>\ud83e\uddf0 <strong>Scadenza per la presentazione del BOM:<\/strong> 15 ottobre (pre-acquisto facoltativo dei componenti)<\/li>\n\n\n\n<li>\ud83d\udca1 <strong>Scadenza per la prenotazione:<\/strong> 18 ottobre<\/li>\n<\/ul>\n\n\n\n<p>Entrambi <strong>di persona<\/strong> E <strong>partecipazione a distanza<\/strong> sono supportati. I team remoti possono spedire i loro prototipi a Leopoli per test professionali in loco.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Finanziamenti e premi<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\ud83d\udcb0 <strong>Budget per la ricerca e sviluppo:<\/strong> 8.000\u201310.000 UAH per squadra approvata<\/li>\n\n\n\n<li>\ud83c\udfc6 <strong>Primo premio:<\/strong> 40.000 UAH per la soluzione anti-drone pi\u00f9 efficace<\/li>\n<\/ul>\n\n\n\n<p>Le squadre selezionate possono anche ricevere <strong>finanziamento diretto della difesa<\/strong> per una continua ricerca e sviluppo oltre la concorrenza, indipendentemente dal posizionamento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Integrazione strategica e partner<\/strong><\/h3>\n\n\n\n<p>Gli sponsor dell&#039;evento offrono opportunit\u00e0 di integrazione uniche, tra cui:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>ComBat.vision<\/strong> \u2013 Integrazione del Battlefield Management System (BMS) per il punteggio bonus<\/li>\n\n\n\n<li><strong>Vujko.net<\/strong> \u2013 Capacit\u00e0 di assistenza alla detonazione a distanza<\/li>\n\n\n\n<li><strong>Tecnologia di difesa per l&#039;Ucraina<\/strong>, <strong>Laboratori Kaizen<\/strong>, E <strong>Libert\u00e0 made in America<\/strong> \u2013 Sponsor principali dell\u2019evento che supportano l\u2019innovazione a lungo termine contro i droni<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Criteri di valutazione<\/strong><\/h3>\n\n\n\n<p>I progetti saranno valutati in base a:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Efficacia anti-drone e integrazione del sistema acustico<\/li>\n\n\n\n<li>Efficienza dei costi e approvvigionamento dei componenti<\/li>\n\n\n\n<li>Velocit\u00e0 di distribuzione e portabilit\u00e0<\/li>\n\n\n\n<li>Innovazione e scalabilit\u00e0 per le condizioni di campo<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Unisciti alla rivoluzione tecnologica della difesa<\/strong><\/h3>\n\n\n\n<p>Da <strong>25-27 ottobre<\/strong>, ingegneri, ricercatori della difesa e innovatori collaboreranno per progettare e dimostrare soluzioni pratiche in grado di <strong>rilevamento, interruzione e neutralizzazione di UAV abilitati alla fibra<\/strong>.<\/p>\n\n\n\n<p>Questa iniziativa rappresenta pi\u00f9 di una semplice innovazione: \u00e8 un contributo diretto alla difesa dell&#039;Ucraina e un passo avanti verso la garanzia del futuro della tecnologia bellica.<\/p>\n\n\n\n<p><strong>Unisciti alla missione. Costruisci la tecnologia che salva vite umane.<\/strong><\/p>\n\n\n\n<p>\ud83d\udd17 Scopri di pi\u00f9 e <a href=\"https:\/\/kaizentechlabs.us\/2025\/09\/22\/iobt-hackathon-2025\/\" data-type=\"link\" data-id=\"https:\/\/kaizentechlabs.us\/2025\/09\/22\/iobt-hackathon-2025\/\" target=\"_blank\" rel=\"noopener\">registro<\/a> Attraverso <strong><a href=\"https:\/\/kaizentechlabs.us\/2025\/09\/22\/iobt-hackathon-2025\/\" data-type=\"link\" data-id=\"https:\/\/kaizentechlabs.us\/2025\/09\/22\/iobt-hackathon-2025\/\" target=\"_blank\" rel=\"noopener\">Kaizen Labs IOBT 2025<\/a><\/strong>.<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Ukraine\u2019s technological front is gearing up for a new wave of battlefield innovation. Kaizen Labs, in partnership with Defense Tech for Ukraine, American Made Freedom, and other leading defense organizations, has announced the Anti-Fiber Drone Technologies Hackathon, a 72-hour engineering challenge to develop field-ready counter-UAV systems against fiber optic drone threats. Innovating for the Modern [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":3294,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[46,45,43,42,39,44],"class_list":["post-3293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-product-development","tag-46","tag-anti-drone","tag-drone","tag-drones","tag-fiber-optic","tag-hackathon"],"acf":[],"_links":{"self":[{"href":"https:\/\/defensetechforukraine.org\/it\/wp-json\/wp\/v2\/posts\/3293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/defensetechforukraine.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/defensetechforukraine.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/defensetechforukraine.org\/it\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/defensetechforukraine.org\/it\/wp-json\/wp\/v2\/comments?post=3293"}],"version-history":[{"count":2,"href":"https:\/\/defensetechforukraine.org\/it\/wp-json\/wp\/v2\/posts\/3293\/revisions"}],"predecessor-version":[{"id":3320,"href":"https:\/\/defensetechforukraine.org\/it\/wp-json\/wp\/v2\/posts\/3293\/revisions\/3320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/defensetechforukraine.org\/it\/wp-json\/wp\/v2\/media\/3294"}],"wp:attachment":[{"href":"https:\/\/defensetechforukraine.org\/it\/wp-json\/wp\/v2\/media?parent=3293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/defensetechforukraine.org\/it\/wp-json\/wp\/v2\/categories?post=3293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/defensetechforukraine.org\/it\/wp-json\/wp\/v2\/tags?post=3293"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}