{"id":3191,"date":"2025-10-14T13:41:03","date_gmt":"2025-10-14T13:41:03","guid":{"rendered":"https:\/\/defensetechforukraine.org\/?p=3191"},"modified":"2025-10-25T06:24:08","modified_gmt":"2025-10-25T06:24:08","slug":"the-west-must-finance-freedom","status":"publish","type":"post","link":"https:\/\/defensetechforukraine.org\/de\/delegation\/the-west-must-finance-freedom\/","title":{"rendered":"Der Westen muss die Freiheit finanzieren"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3191\" class=\"elementor elementor-3191\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f33fa22 e-flex e-con-boxed e-con e-parent\" data-id=\"4f33fa22\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6bb6a696 elementor-widget elementor-widget-text-editor\" data-id=\"6bb6a696\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>DEFENSE TECH FOR UKRAINE 2025 DELEGATIONSBERICHT<\/strong><\/p>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>28. September 2025<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:image {\"id\":3192,\"sizeSlug\":\"large\",\"linkDestination\":\"none\"} --><\/p>\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" class=\"wp-image-3192\" src=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-1024x768.png\" alt=\"\" srcset=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-1024x768.png 1024w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-300x225.png 300w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-768x576.png 768w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-16x12.png 16w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<p><!-- \/wp:image --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Defense Tech for Ukraine (DTU), eine internationale, von Freiwilligen gef\u00fchrte Non-Profit-Organisation, die die Entwicklung und Verbreitung wichtiger Technologien f\u00fcr die ukrainische Verteidigung vorantreibt, ist derzeit in der Ukraine, um ihre Mission voranzutreiben. Vierzehn DTU-Mitglieder aus den USA, Gro\u00dfbritannien und Kanada besuchten zwei Wochen lang Verteidigungskonferenzen, vernetzten ukrainische R\u00fcstungshersteller mit westlichen Investoren und halfen mehreren ukrainischen Milit\u00e4reinheiten bei der Bew\u00e4ltigung kritischer technischer und finanzieller Herausforderungen. Die Kernaufgabe der Gruppe: die Verbesserung der Qualit\u00e4t und Quantit\u00e4t der Ausr\u00fcstung der ukrainischen Verteidigungskr\u00e4fte.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Der Aufenthalt der Delegation in der Ukraine war \u00e4u\u00dferst produktiv und brachte eine F\u00fclle neuer Informationen, wichtige Partnerschaften und die Best\u00e4tigung der Notwendigkeit des einzigartigen Prozesses der DTU zur Unterst\u00fctzung der ukrainischen Verteidigungsindustrie. Vier Mitglieder blieben in der Ukraine, w\u00e4hrend die \u00fcbrigen in ihre Heimat zur\u00fcckkehrten, um die Delegation aus der Ferne zu unterst\u00fctzen.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:heading {\"level\":3} --><\/p>\n<h3 class=\"wp-block-heading\"><strong><strong>Wichtige Verbindungen<\/strong><\/strong><\/h3>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><b>\u2013 14 internationale Investoren<\/b> im Bereich Verteidigungstechnologie (d\u00e4nisch, amerikanisch, britisch, deutsch und franz\u00f6sisch) wurden kontaktiert. D\u00e4nische Investoren waren am engagiertesten, was mit den Erfahrungen der DTU sowohl bei der IT Arena als auch beim Defense Tech Valley in Lviv sowie bei den Sitzungen des Europ\u00e4ischen Parlaments in Br\u00fcssel Anfang des Jahres \u00fcbereinstimmt.<br><b>\u2013 37 ukrainische R\u00fcstungshersteller<\/b> wurden dem Herstellernetzwerk der DTU hinzugef\u00fcgt und decken ein breites Spektrum an Technologien ab: Drohnen (Luft und Boden), elektronische Kriegsf\u00fchrung\/St\u00f6rsysteme, vernetzte digitale Kommunikation, KI-gest\u00fctzte Gefechtsfeld\u00fcberwachung, integrierte Befehls- und Kontrollsysteme und mehr.<br><b>\u2013 Einflussreiche Verb\u00fcndete<\/b>, darunter der Leiter von Brave1, Professoren des Lviv Polytechnic und der Kyiv School of Economics sowie andere, hier nicht genannte Personen.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:image {\"id\":3193,\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} --><\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"588\" height=\"608\" class=\"wp-image-3193\" src=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-1.png\" alt=\"\" srcset=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-1.png 588w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-1-290x300.png 290w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-1-12x12.png 12w\" sizes=\"(max-width: 588px) 100vw, 588px\" \/><p><\/p>\n<figcaption class=\"wp-element-caption\"><em>Nichole Robichaux von der DTU h\u00e4lt eine fortschrittliche FPV-Drohne in der Drohnenwerkstatt einer ukrainischen Milit\u00e4reinheit<p><\/p>\n<\/em><p><em><\/em><\/p><\/figcaption>\n<\/figure>\n<p><!-- \/wp:image --><\/p>\n<p><!-- wp:heading {\"level\":3} --><\/p>\n<h3 class=\"wp-block-heading\"><strong>Verteidigungskonferenzen<\/strong><\/h3>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Die DTU nahm an zwei gro\u00dfen verteidigungsbezogenen Konferenzen in Lviv teil:<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:list --><\/p>\n<ul class=\"wp-block-list\">\n<li style=\"list-style-type: none;\">\n<ul class=\"wp-block-list\"><!-- wp:list-item --><\/ul>\n<\/li>\n<\/ul>\n<ul class=\"wp-block-list\">\n<li style=\"list-style-type: none;\">\n<ul class=\"wp-block-list\">\n<li><strong>Brave1 Defense Tech Valley<\/strong> (16.\u201317. September): <a href=\"https:\/\/defensevalley.tech\" target=\"_blank\" rel=\"noopener\"><mark class=\"has-inline-color has-vivid-cyan-blue-color\" style=\"background-color: rgba(0, 0, 0, 0);\">https:\/\/defensevalley.tech<\/mark><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><!-- \/wp:list-item --><\/p>\n<p><!-- wp:list-item --><\/p>\n<ul class=\"wp-block-list\">\n<li style=\"list-style-type: none;\">\n<ul class=\"wp-block-list\">\n<li><strong>IT Arena<\/strong> (26.\u201328. September): <a href=\"https:\/\/itarena.ua\" target=\"_blank\" rel=\"noopener\"><mark class=\"has-inline-color has-vivid-cyan-blue-color\" style=\"background-color: rgba(0, 0, 0, 0);\">https:\/\/itarena.ua<\/mark><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><!-- \/wp:list-item --><\/p>\n<p><!-- \/wp:list --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:image {\"id\":3194,\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} --><\/p>\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"920\" height=\"629\" class=\"wp-image-3194\" src=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-2.png\" alt=\"\" srcset=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-2.png 920w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-2-300x205.png 300w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-2-768x525.png 768w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-2-18x12.png 18w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><p><\/p>\n<figcaption class=\"wp-element-caption\"><em>Alex Hebbe von Monava beschreibt Carl Larson von der DTU ihren akustischen Drohnendetektor<p><\/p>\n<\/em><p><em><\/em><\/p><\/figcaption>\n<\/figure>\n<p><!-- \/wp:image --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Auf der Brave1 kn\u00fcpfte die DTU \u00fcber ihren Stand und ihre Networking-Lounge Kontakte zu \u00fcber 100 Personen. Zu den namhaften Kontakten z\u00e4hlten der Leiter von Brave1, ukrainische Rechtsexperten f\u00fcr Export und Unternehmensgr\u00fcndung, mehrere Drohnenkommandanten, milit\u00e4rische Forschungs- und Entwicklungsteams, eine Drohnenschule f\u00fcr Spezialeinheiten sowie zahlreiche europ\u00e4ische Risikokapitalfirmen, die am ukrainischen Verteidigungssektor interessiert sind.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Bei der IT Arena konzentrierte sich die Delegation stark auf westliche Investoren, bezog aber auch wichtige ukrainische Interessenvertreter ein: den Direktor f\u00fcr digitale Transformation im Verteidigungsministerium, den Leiter der wissenschaftlichen Forschung und Entwicklung am Polytechnikum Lviv und verteidigungsorientierte Lehrkr\u00e4fte der Wirtschaftsschule Kiew.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:image {\"id\":3196,\"sizeSlug\":\"large\",\"linkDestination\":\"none\"} --><\/p>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" class=\"wp-image-3196\" src=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-3-1024x577.png\" alt=\"\" srcset=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-3-1024x577.png 1024w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-3-300x169.png 300w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-3-768x432.png 768w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-3-1536x865.png 1536w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-3-18x10.png 18w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-3.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><p><\/p>\n<figcaption class=\"wp-element-caption\"><em>Das DTU-Delegationsteam und Verb\u00fcndete auf der Brave1 Defense Tech Valley-Konferenz<p><\/p>\n<\/em><p><em><\/em><\/p><\/figcaption>\n<\/figure>\n<p><!-- \/wp:image --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Beide Ereignisse best\u00e4tigten nachdr\u00fccklich die Einsch\u00e4tzung der DTU, dass die F\u00f6rderung internationaler Finanzierung der ukrainischen R\u00fcstungsindustrie der wirksamste Weg zum Schutz des ukrainischen Lebens und der Freiheit ist. Andere Akteure kommen zu demselben Schluss:<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:list --><\/p>\n<ul class=\"wp-block-list\">\n<li style=\"list-style-type: none;\">\n<ul class=\"wp-block-list\"><!-- wp:list-item --><\/ul>\n<\/li>\n<\/ul>\n<ul class=\"wp-block-list\">\n<li style=\"list-style-type: none;\">\n<ul class=\"wp-block-list\">\n<li><em>MITS Capital gr\u00fcndet die d\u00e4nisch-ukrainische Allianz MITS Industries, die Tencore, Infozahyst, Unwave und weitere zusammenbringt<\/em><mark class=\"has-inline-color has-vivid-cyan-blue-color\" style=\"background-color: rgba(0, 0, 0, 0);\"> <a href=\"https:\/\/thedefender.media\/en\/2025\/09\/mits-capital-launches-mits-industries\/\" target=\"_blank\" rel=\"noopener\">https:\/\/thedefender.media\/en\/2025\/09\/mits-capital-launches-mits-industries\/<\/a>&nbsp;&nbsp;<\/mark><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><!-- \/wp:list-item --><\/p>\n<p><!-- wp:list-item --><\/p>\n<ul class=\"wp-block-list\">\n<li style=\"list-style-type: none;\">\n<ul class=\"wp-block-list\">\n<li><em>MITS Capital vereint f\u00fchrende Vertreter der ukrainischen Verteidigungstechnologie unter dem Dach von MITS Industries <\/em><mark class=\"has-inline-color has-vivid-cyan-blue-color\" style=\"background-color: rgba(0, 0, 0, 0);\"><a href=\"https:\/\/www.kyivpost.com\/post\/60336\" target=\"_blank\" rel=\"noopener\">https:\/\/www.kyivpost.com\/post\/60336<\/a>&nbsp;<\/mark>&nbsp;<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><!-- \/wp:list-item --><\/p>\n<p><!-- wp:list-item --><\/p>\n<ul class=\"wp-block-list\">\n<li style=\"list-style-type: none;\">\n<ul class=\"wp-block-list\">\n<li><em>Die von der NATO vorgeschlagene globale Verteidigungsbank <\/em><a href=\"https:\/\/www.reuters.com\/sustainability\/boards-policy-regulation\/deutsche-bank-backs-proposed-global-defence-bank-2025-09-17\/\" target=\"_blank\" rel=\"noopener\"><mark class=\"has-inline-color has-vivid-cyan-blue-color\" style=\"background-color: rgba(0, 0, 0, 0);\">https:\/\/www.reuters.com\/sustainability\/boards-policy-regulation\/deutsche-bank-backs-proposed-global-defence-bank-2025-09-17\/<\/mark><\/a>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><!-- \/wp:list-item --><\/p>\n<p><!-- \/wp:list --><\/p>\n<p><!-- wp:heading {\"level\":3} --><\/p>\n<h3 class=\"wp-block-heading\"><strong>Von der DTU unterst\u00fctzte Projekte<\/strong><\/h3>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>DTU war stolz, mehrere der von ihr unterst\u00fctzten Hersteller auf der Brave1-Konferenz begr\u00fc\u00dfen zu d\u00fcrfen:<br>\u2013 Kaizen Labs (Ukraine): Akustische Drohnendetektoren, Glasfaserkabelschneider und mehr.<br>\u2013 Freiwillige medizinische Versorgung (Ukraine): Schnell einsetzbare Tragen.<br>\u2013 Monava (Schweden): Akustische Drohnendetektoren (Manpack-Systeme).<br>\u2013 Milit\u00e4rische Fertigung (USA): R\u00fccksto\u00dffreie, auf Drohnen montierte Schrotflinten.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:image {\"id\":3199,\"sizeSlug\":\"large\",\"linkDestination\":\"none\"} --><\/p>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" class=\"wp-image-3199\" src=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-6-1024x640.png\" alt=\"\" srcset=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-6-1024x640.png 1024w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-6-300x188.png 300w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-6-768x480.png 768w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-6-18x12.png 18w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-6.png 1078w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><p><\/p>\n<figcaption class=\"wp-element-caption\"><em>Preston Zen von Kaizen Labs beschreibt Carl Larson von DTU ihren Produktmix<p><\/p>\n<\/em><p><em><\/em><\/p><\/figcaption>\n<\/figure>\n<p><!-- \/wp:image --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Der Stand erregte gro\u00dfes Interesse. So forderten beispielsweise f\u00fcnf ukrainische Milit\u00e4reinheiten Tests des Drone Sentinel-Detektors von Kaizen Labs an, der mithilfe der DTU in einer privaten Einrichtung in der N\u00e4he von Lviv mit vielversprechenden Ergebnissen getestet wurde. Monava meldete \u00fcber 200 Neubestellungen f\u00fcr seinen Manpack-Detektor, direkt nach der Pr\u00e4sentation am DTU-Stand \u2013 ein Ergebnis, das auf dem Schlachtfeld zweifellos Leben retten wird.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:image {\"id\":3198,\"sizeSlug\":\"large\",\"linkDestination\":\"none\"} --><\/p>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" class=\"wp-image-3198\" src=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-5-1024x577.png\" alt=\"\" srcset=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-5-1024x577.png 1024w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-5-300x169.png 300w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-5-768x432.png 768w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-5-1536x865.png 1536w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-5-18x10.png 18w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-5.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><p><\/p>\n<figcaption class=\"wp-element-caption\"><em>Hochmodernes UGV (Bodendrohne) zur Minenr\u00e4umung auf der IT Arena-Konferenz in Lviv<p><\/p>\n<\/em><p><em><\/em><\/p><\/figcaption>\n<\/figure>\n<p><!-- \/wp:image --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:image {\"id\":3200,\"sizeSlug\":\"large\",\"linkDestination\":\"none\"} --><\/p>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" class=\"wp-image-3200\" src=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-7-1024x577.png\" alt=\"\" srcset=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-7-1024x577.png 1024w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-7-300x169.png 300w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-7-768x432.png 768w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-7-1536x865.png 1536w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-7-18x10.png 18w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-7.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><p><\/p>\n<figcaption class=\"wp-element-caption\"><em>Ein ukrainischer Startup-Investitions-Pitch auf der IT Arena-Konferenz in Lviv<p><\/p>\n<\/em><p><em><\/em><\/p><\/figcaption>\n<\/figure>\n<p><!-- \/wp:image --><\/p>\n<p><!-- wp:heading {\"level\":3} --><\/p>\n<h3 class=\"wp-block-heading\"><strong>Kiew-Verbindungen<\/strong><\/h3>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>In Kiew hat die Delegation:<br>\u2013 Besichtigung einer UGV-Produktionsanlage.<br>\u2013 Treffen mit DTU-Mitgliedern, die Abfangdrohnen entwickeln.<br>\u2013 Zusammenarbeit mit Soldaten und Offizieren bei der Arbeit an digitalen Kommunikations- und F&amp;E-Projekten.<br>\u2013 Verbunden mit Mitgliedern des Snake Island Institute und anderen Verb\u00fcndeten.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:image {\"id\":3201,\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} --><\/p>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"673\" height=\"605\" class=\"wp-image-3201\" src=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-8.png\" alt=\"\" srcset=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-8.png 673w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-8-300x270.png 300w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-8-13x12.png 13w\" sizes=\"(max-width: 673px) 100vw, 673px\" \/><p><\/p>\n<figcaption class=\"wp-element-caption\"><em>Carl Larson von der DTU in der UGV-Fabrik des Industrial Bureau<p><\/p>\n<\/em><p><em><\/em><\/p><\/figcaption>\n<\/figure>\n<p><!-- \/wp:image --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Diese Arbeit wurde trotz eines Drohnenangriffs der Shahed-Drohne auf Kiew w\u00e4hrend der ersten Nacht der Delegation in der Stadt fortgesetzt, wobei eine Drohne nur 500 m vom Hotel entfernt abgefangen wurde.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:image {\"id\":3202,\"sizeSlug\":\"large\",\"linkDestination\":\"none\"} --><\/p>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" class=\"wp-image-3202\" src=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-9-1024x577.png\" alt=\"\" srcset=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-9-1024x577.png 1024w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-9-300x169.png 300w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-9-768x432.png 768w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-9-1536x865.png 1536w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-9-18x10.png 18w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-9.png 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><p><\/p>\n<figcaption class=\"wp-element-caption\"><em>Die DTU-Mitglieder Roy Gardiner und Alexander Drueke untersuchen in Kiew eine russische Glasfaserdrohne vom Typ \u201ePrince Vandal\u201c.<p><\/p>\n<\/em><p><em><\/em><\/p><\/figcaption>\n<\/figure>\n<p><!-- \/wp:image --><\/p>\n<p><!-- wp:heading {\"level\":3} --><\/p>\n<h3 class=\"wp-block-heading\"><strong>Furchtloses Charkiw<\/strong><\/h3>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Die Delegation verbrachte au\u00dferdem vier Tage in Charkiw und traf dort mit angesehenen Milit\u00e4reinheiten wie Kraken und der 13. NGU Khartia, Forschungs- und Entwicklungslaboren, Drohnenreparaturwerkst\u00e4tten und dem Gesch\u00e4ftsf\u00fchrer des Charkiwer IT-Clusters zusammen. Wichtige Lieferungen wurden an eine Frontverteidigungseinheit geliefert.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:image {\"id\":3203,\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} --><\/p>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"607\" class=\"wp-image-3203\" src=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-10.png\" alt=\"\" srcset=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-10.png 1020w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-10-300x179.png 300w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-10-768x457.png 768w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-10-18x12.png 18w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/><p><\/p>\n<figcaption class=\"wp-element-caption\"><em>DTU liefert 5 Starlinks an eine Fronteinheit in der N\u00e4he von Charkiw<\/em><\/figcaption>\n<\/figure>\n<p><!-- \/wp:image --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Das Team nahm auch wieder Kontakt zu ehemaligen Kameraden von Carl Larson auf, die noch immer an der Front dienen.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:image {\"id\":3204,\"sizeSlug\":\"large\",\"linkDestination\":\"none\"} --><\/p>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"555\" class=\"wp-image-3204\" src=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-11-1024x555.png\" alt=\"\" srcset=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-11-1024x555.png 1024w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-11-300x163.png 300w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-11-768x416.png 768w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-11-18x10.png 18w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-11.png 1078w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><p><\/p>\n<figcaption class=\"wp-element-caption\"><em>Larson und Robichaux von der DTU unterst\u00fctzen eine internationale Spezialeinheit nahe der Front in Charkiw<\/em><\/figcaption>\n<\/figure>\n<p><!-- \/wp:image --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Neben den Treffen besichtigte das Team schwer besch\u00e4digte n\u00f6rdliche Stadtviertel nur wenige Kilometer von der Front entfernt. In der letzten Nacht der Reise wurde Charkiw von einer Angriffswelle von \u00fcber 40 Schaheds heimgesucht, von denen 17 in der Stadt landeten. Die Bewohner f\u00fchrten ruhig die Verdunkelungsma\u00dfnahmen aus, bewachten die Flugabwehr und gingen ihrem Alltag nach \u2013 ein beeindruckendes Beispiel f\u00fcr Widerstandsf\u00e4higkeit.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:heading {\"level\":3} --><\/p>\n<h3 class=\"wp-block-heading\"><strong>Abschluss<\/strong><\/h3>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Die Pr\u00e4senz der DTU in der Ukraine hat die entscheidende Bedeutung der internationalen Zusammenarbeit und der direkten Unterst\u00fctzung ukrainischer Verteidigungsinnovatoren unterstrichen. Es ist offensichtlich, dass moderne Technologie in den Kriegen des 21. Jahrhunderts eine entscheidende Rolle spielt. Der angesehenste Milit\u00e4rkommandeur der Ukraine, der ehemalige ukrainische Oberbefehlshaber General Valerii Zaluzhnyi, hat erkl\u00e4rt, dass der technologische Fortschritt \u00fcber den Sieg des aktuellen Krieges entscheiden wird. Internationale Partner, Investoren und gemeinn\u00fctzige Vermittler wie die DTU werden eine \u00fcberragende Rolle beim Erfolg auf dem Schlachtfeld spielen, der es der Ukraine erm\u00f6glicht, aus einer Position der St\u00e4rke zu verhandeln. Das fehlende entscheidende Bindeglied, n\u00e4mlich Investitionen von au\u00dferhalb des westlichen Kapitals in den aufstrebenden ukrainischen Verteidigungssektor, ist eine attraktive Gelegenheit f\u00fcr westliche Investoren und bietet gleichzeitig die M\u00f6glichkeit, die Ostflanke der Demokratie zu st\u00e4rken. In Zukunft wird sich die DTU stark auf die wichtige Arbeit konzentrieren, den ukrainischen Verteidigungssektor mit westlichen Kapitalquellen zu verbinden.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Defense Tech for Ukraine ist weiterhin zutiefst geehrt, dem ukrainischen Volk in seinem Kampf f\u00fcr Souver\u00e4nit\u00e4t, Kultur und Freiheit zur Seite zu stehen. Herzlichen Dank an alle, die diese Mission erm\u00f6glicht haben, und an diejenigen, die sich verpflichtet haben, die Ukraine zu unterst\u00fctzen, bis der letzte Eindringling von ihrem Boden vertrieben ist. Slava Ukraini!<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><strong>Carl Larson, Jonathan Lippert und das gesamte F\u00fchrungsteam von Defense Tech for Ukraine<\/strong><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:image {\"id\":3205,\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} --><\/p>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"876\" height=\"384\" class=\"wp-image-3205\" src=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-12.png\" alt=\"\" srcset=\"https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-12.png 876w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-12-300x132.png 300w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-12-768x337.png 768w, https:\/\/defensetechforukraine.org\/wp-content\/uploads\/2025\/10\/image-12-18x8.png 18w\" sizes=\"(max-width: 876px) 100vw, 876px\" \/><\/figure>\n<p><!-- \/wp:image --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:heading {\"level\":3} --><\/p>\n<h3 class=\"wp-block-heading\"><strong><p><\/p>\n<\/strong><p><strong>Referenzlinks<\/strong><\/p><\/h3>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:list --><\/p>\n<ul class=\"wp-block-list\">\n<li style=\"list-style-type: none;\">\n<ul class=\"wp-block-list\"><!-- wp:list-item --><\/ul>\n<\/li>\n<\/ul>\n<ul class=\"wp-block-list\">\n<li style=\"list-style-type: none;\">\n<ul class=\"wp-block-list\">\n<li>Neuer Verteidigungsposten des European Defense Tech Hub <a href=\"https:\/\/new-defense.com\/defense-tech-valley-2025-the-frontline-of-defense-innovation\/\" target=\"_blank\" rel=\"noopener\"><mark class=\"has-inline-color has-vivid-cyan-blue-color\" style=\"background-color: rgba(0, 0, 0, 0);\">https:\/\/new-defense.com\/defense-tech-valley-2025-the-frontline-of-defense-innovation<\/mark><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><!-- \/wp:list-item --><\/p>\n<p><!-- wp:list-item --><\/p>\n<ul class=\"wp-block-list\">\n<li style=\"list-style-type: none;\">\n<ul class=\"wp-block-list\">\n<li>Die ukrainischen Startups Ovul, HEFT und StackBob gewinnen $30k beim Startup-Wettbewerb IT Arena 2025 <a href=\"https:\/\/www.vestbee.com\/insights\/articles\/ovul-heft-and-stack-bob-win-30k\" target=\"_blank\" rel=\"noopener\"><mark class=\"has-inline-color has-vivid-cyan-blue-color\" style=\"background-color: rgba(0, 0, 0, 0);\">https:\/\/www.vestbee.com\/insights\/articles\/ovul-heft-and-stack-bob-win-30k<\/mark><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><!-- \/wp:list-item --><\/p>\n<p><!-- wp:list-item --><\/p>\n<ul class=\"wp-block-list\">\n<li style=\"list-style-type: none;\">\n<ul class=\"wp-block-list\">\n<li>MITS Capital gr\u00fcndet die d\u00e4nisch-ukrainische Allianz MITS Industries, die Tencore, Infozahyst, Unwave und weitere zusammenbringt <a href=\"https:\/\/thedefender.media\/en\/2025\/09\/mits-capital-launches-mits-industries\/\" target=\"_blank\" rel=\"noopener\"><mark class=\"has-inline-color has-vivid-cyan-blue-color\" style=\"background-color: rgba(0, 0, 0, 0);\">https:\/\/thedefender.media\/en\/2025\/09\/mits-capital-launches-mits-industries<\/mark><\/a>&nbsp;&nbsp;<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><!-- \/wp:list-item --><\/p>\n<p><!-- wp:list-item --><\/p>\n<ul class=\"wp-block-list\">\n<li style=\"list-style-type: none;\">\n<ul class=\"wp-block-list\">\n<li>MITS Capital vereint f\u00fchrende Vertreter der ukrainischen Verteidigungstechnologie unter dem Dach von MITS Industries <a href=\"https:\/\/www.kyivpost.com\/post\/60336\" target=\"_blank\" rel=\"noopener\"><mark class=\"has-inline-color has-vivid-cyan-blue-color\" style=\"background-color: rgba(0, 0, 0, 0);\">https:\/\/www.kyivpost.com\/post\/60336<\/mark><\/a>&nbsp;&nbsp;<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><!-- \/wp:list-item --><\/p>\n<p><!-- wp:list-item --><\/p>\n<ul class=\"wp-block-list\">\n<li style=\"list-style-type: none;\">\n<ul class=\"wp-block-list\">\n<li>Deutsche Bank unterst\u00fctzt geplante globale Verteidigungsbank <a href=\"https:\/\/www.reuters.com\/sustainability\/boards-policy-regulation\/deutsche-bank-backs-proposed-global-defence-bank-2025-09-17\/\" target=\"_blank\" rel=\"noopener\"><mark class=\"has-inline-color has-vivid-cyan-blue-color\" style=\"background-color: rgba(0, 0, 0, 0);\">https:\/\/www.reuters.com\/sustainability\/boards-policy-regulation\/deutsche-bank-backs-proposed-global-defence-bank-2025-09-17<\/mark><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><!-- \/wp:list-item --><\/p>\n<p><!-- \/wp:list --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>DEFENSE TECH FOR UKRAINE 2025 DELEGATION REPORT September 28, 2025 Defense Tech for Ukraine (DTU), an international volunteer-run nonprofit working to accelerate the development and spread of critical technology for Ukraine\u2019s defense, is currently in Ukraine advancing its mission. Fourteen DTU members from the US, UK, and Canada for two weeks attended defense conferences, connected [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3192,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[59],"tags":[],"class_list":["post-3191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-delegation"],"acf":[],"_links":{"self":[{"href":"https:\/\/defensetechforukraine.org\/de\/wp-json\/wp\/v2\/posts\/3191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/defensetechforukraine.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/defensetechforukraine.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/defensetechforukraine.org\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/defensetechforukraine.org\/de\/wp-json\/wp\/v2\/comments?post=3191"}],"version-history":[{"count":22,"href":"https:\/\/defensetechforukraine.org\/de\/wp-json\/wp\/v2\/posts\/3191\/revisions"}],"predecessor-version":[{"id":3546,"href":"https:\/\/defensetechforukraine.org\/de\/wp-json\/wp\/v2\/posts\/3191\/revisions\/3546"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/defensetechforukraine.org\/de\/wp-json\/wp\/v2\/media\/3192"}],"wp:attachment":[{"href":"https:\/\/defensetechforukraine.org\/de\/wp-json\/wp\/v2\/media?parent=3191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/defensetechforukraine.org\/de\/wp-json\/wp\/v2\/categories?post=3191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/defensetechforukraine.org\/de\/wp-json\/wp\/v2\/tags?post=3191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}